{"id":29472,"date":"2022-06-07T11:39:33","date_gmt":"2022-06-07T10:39:33","guid":{"rendered":"https:\/\/guineechrono.com\/?p=29472"},"modified":"2022-06-07T11:40:03","modified_gmt":"2022-06-07T10:40:03","slug":"guinee-ministere-de-la-securite-plusieurs-responsables-nommes","status":"publish","type":"post","link":"https:\/\/guineechrono.com\/index.php\/guinee-ministere-de-la-securite-plusieurs-responsables-nommes\/","title":{"rendered":"Guin\u00e9e\/Minist\u00e8re de la s\u00e9curit\u00e9 : plusieurs responsables nomm\u00e9s"},"content":{"rendered":"<p><strong>Dans un d\u00e9cret lu hier soir \u00e0 la t\u00e9l\u00e9vision nationale, le pr\u00e9sident de la transition, Colonel Mamadi Doumbouya a fait le grand m\u00e9nage \u00e0 la t\u00eate des groupements de police tant \u00e0 Conakry qu\u2019\u00e0 l\u2019int\u00e9rieur du pays.<\/strong><\/p>\n<p><strong style=\"font-style: inherit;\">Lisez\u2026 <\/strong><\/p>\n<p><strong>Groupement num\u00e9ro 1 de Kaloum<\/strong><\/p>\n<p><strong style=\"font-style: inherit;\">Commandant : <\/strong>Edouarim Sow, commissaire principal de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Commandant adjoint\u00a0:<\/strong> Seydou Konat\u00e9, commissaire centrale de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Groupement num\u00e9ro 2 de Bamb\u00e9to<\/strong><\/p>\n<p><strong style=\"font-style: inherit;\">Commandant :<\/strong> Mamadou Aliou Diallo, commissaire principal de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS ;<\/p>\n<p><strong style=\"font-style: inherit;\">Commandant adjoint\u00a0: <\/strong>Soriba Soumah, commissaire principal de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Groupement num\u00e9ro 3 de Enco 5<\/strong><\/p>\n<p><strong style=\"font-style: inherit;\">Commandant : <\/strong>Tamba Robert Tolno, commissaire principal de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS ;<\/p>\n<p><strong style=\"font-style: inherit;\">Commandant adjoint <\/strong>: Sory Cond\u00e9, commissaire principal de police, pr\u00e9c\u00e9demment en service au commissariat central de Dubr\u00e9ka\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Groupement num\u00e9ro 4 de Cimenterie<\/strong><\/p>\n<p><strong style=\"font-style: inherit;\">Commandant : <\/strong>Salomon Williams, commissaire principal de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Commandant adjoint <\/strong>:\u00a0Saidou Compo, commissaire principal de police, pr\u00e9c\u00e9demment en service au commissariat central de Coyah\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Groupement num\u00e9ro 5 de Kindia<\/strong><\/p>\n<p><strong style=\"font-style: inherit;\">Commandant : <\/strong>Alphonse Goumou, commissaire divisionnaire de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Commandant adjoint : <\/strong>Alhassane\u00a0Bah, commissaire principal de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Groupement num\u00e9ro 6 de Bok\u00e9<\/strong><\/p>\n<p><strong style=\"font-style: inherit;\">Commandant : <\/strong>Mamadou Mouctar\u00a0Ly, commissaire divisionnaire de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Commandant adjoint : <\/strong>Lansana Traor\u00e9, commissaire principal, pr\u00e9c\u00e9demment commandant de la CMIS num\u00e9ro 10 de Mamou\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Groupement num\u00e9ro 7 de Lab\u00e9<\/strong><\/p>\n<p><strong style=\"font-style: inherit;\">Commandant\u00a0: <\/strong>Ibrahima Sory Cont\u00e9, commissaire principal de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Commandant adjoint\u00a0: <\/strong>P\u00e9ma Deveto Bilivogui, commissaire de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale de la S\u00e9curit\u00e9 publique\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Groupement num\u00e9ro 8 de Kankan<\/strong><\/p>\n<p><strong style=\"font-style: inherit;\">Commandant\u00a0: <\/strong>Saidou Kaba, commissaire principal de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Commandant adjoint\u00a0: <\/strong>Alpha Oumar Keita, commissaire principal de police, pr\u00e9c\u00e9demment en service \u00e0 la CMIS num\u00e9ro 25 de Coyah\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Groupement num\u00e9ro 9 de N\u2019Z\u00e9r\u00e9kor\u00e9<\/strong><\/p>\n<p><strong style=\"font-style: inherit;\">Commandant : <\/strong>Michel Diawara, commissaire principal de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS\u00a0;<\/p>\n<p><strong style=\"font-style: inherit;\">Commandant adjoint\u00a0: <\/strong>Mory Camara, commissaire de police, pr\u00e9c\u00e9demment en service \u00e0 la direction centrale des CMIS<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>R\u00e9daction <\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans un d\u00e9cret lu hier soir \u00e0 la t\u00e9l\u00e9vision nationale, le pr\u00e9sident de la transition, Colonel Mamadi Doumbouya a fait le grand m\u00e9nage \u00e0 la t\u00eate des groupements de police tant \u00e0 Conakry qu\u2019\u00e0 l\u2019int\u00e9rieur du pays. Lisez\u2026 Groupement num\u00e9ro 1 de Kaloum Commandant : Edouarim Sow, commissaire principal de police, pr\u00e9c\u00e9demment en service \u00e0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29473,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"buzzeditor_post_format":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-29472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_featured_media_url":"https:\/\/guineechrono.com\/wp-content\/uploads\/2022\/06\/bachir.webp","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/comments?post=29472"}],"version-history":[{"count":0,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media\/29473"}],"wp:attachment":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media?parent=29472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/categories?post=29472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/tags?post=29472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}