{"id":29566,"date":"2022-06-11T20:27:18","date_gmt":"2022-06-11T19:27:18","guid":{"rendered":"https:\/\/guineechrono.com\/?p=29566"},"modified":"2022-06-11T20:27:18","modified_gmt":"2022-06-11T19:27:18","slug":"pretendue-fuite-de-lepreuve-de-dictee-question-le-men-a-parle-de-fausses-rumeurs","status":"publish","type":"post","link":"https:\/\/guineechrono.com\/index.php\/pretendue-fuite-de-lepreuve-de-dictee-question-le-men-a-parle-de-fausses-rumeurs\/","title":{"rendered":"Pr\u00e9tendue fuite de l\u2019\u00e9preuve de Dict\u00e9e Question : le MEN-A parle de fausses rumeurs"},"content":{"rendered":"<p>Comme \u00e0 leur habitude, des individus commencent \u00e0 faire circuler sur les r\u00e9seaux sociaux, des informations selon lesquelles, il aurait eu fuite de l\u2019\u00e9preuve de Dict\u00e9e Questions du BEPC session 2022.<\/p>\n<p>Les colporteurs de ces rumeurs ne sont et ne pourraient \u00eatre capables d\u2019apporter des preuves de leurs all\u00e9gations, car une fuite de sujet est \u00e9tablie lorsque l\u2019\u00e9preuve se retrouve dehors avant l\u2019heure pr\u00e9vue pour son lancement officiel.<br \/>\nPour l\u2019\u00e9preuve de Dict\u00e9e Questions parce qu\u2019il s\u2019agit d\u2019elle, nous mettons au d\u00e9fi quiconque, de prouver qu\u2019il a re\u00e7u ce sujet avant 9h de ce samedi.<br \/>\nNotre page officielle reste largement ouverte et disponible pour tous ceux qui sont v\u00e9ridiques et qui croient avoir la moindre preuve de leurs affirmations.<br \/>\nEn tout cas jusqu\u2019\u00e0 date, aucun n\u2019a encore \u00e9t\u00e9 capable de prouver ces rumeurs insens\u00e9es.<br \/>\nAlors, si l\u2019objectif des auteurs de ces intox est de cr\u00e9er le trouble dans les esprit et jeter le noir sur le bon d\u00e9roulement de ces examens nationaux session 2022, ils peuvent bien rester tranquilles car le MEPU-A poursuivra en toute s\u00e9r\u00e9nit\u00e9 l\u2019organisation de ces \u00e9valuations nationales et rien ne saurait le distraire et le d\u00e9tourner de ses objectifs qui restent et demeurent ( des examens justes, cr\u00e9dibles et transparents).<br \/>\nLe MEPU-A pense qu\u2019il n\u2019y aura aucune fuite de sujets cette ann\u00e9e vu les nombreuses dispositions prises pour s\u00e9curiser les \u00e9preuves et tout le processus avec.<br \/>\nMalgr\u00e9 tout, si un cas av\u00e9r\u00e9 de fuite se produisait nous ne le souhaitons pas, nous serons les premiers \u00e0 l\u2019annoncer et \u00e0 y apporter des solutions imm\u00e9diates comme l\u2019a \u00e9t\u00e9 par le pass\u00e9, l\u2019oeuvre humaine n\u2019\u00e9tant jamais parfaite.<\/p>\n<p>Le Service de Communication du MEPU-A.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme \u00e0 leur habitude, des individus commencent \u00e0 faire circuler sur les r\u00e9seaux sociaux, des informations selon lesquelles, il aurait eu fuite de l\u2019\u00e9preuve de Dict\u00e9e Questions du BEPC session 2022. Les colporteurs de ces rumeurs ne sont et ne pourraient \u00eatre capables d\u2019apporter des preuves de leurs all\u00e9gations, car une fuite de sujet est [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29567,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"buzzeditor_post_format":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-29566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_featured_media_url":"https:\/\/guineechrono.com\/wp-content\/uploads\/2022\/06\/fraude.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/comments?post=29566"}],"version-history":[{"count":0,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media\/29567"}],"wp:attachment":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media?parent=29566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/categories?post=29566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/tags?post=29566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}