{"id":29585,"date":"2022-06-13T14:32:14","date_gmt":"2022-06-13T13:32:14","guid":{"rendered":"https:\/\/guineechrono.com\/?p=29585"},"modified":"2022-06-13T14:32:14","modified_gmt":"2022-06-13T13:32:14","slug":"boke-11-morts-et-5-blesses-dans-un-accident-de-la-circulation","status":"publish","type":"post","link":"https:\/\/guineechrono.com\/index.php\/boke-11-morts-et-5-blesses-dans-un-accident-de-la-circulation\/","title":{"rendered":"Bok\u00e9 : 11 morts et 5 bless\u00e9s dans un accident de la circulation"},"content":{"rendered":"<p><strong>Onze morts et 5 bless\u00e9s graves, c\u2019est le triste bilan d\u2019un accident de la route survenu ce lundi 13 juin 2022 aux environs de 10 heures dans le secteur Tambony, district Kar\u00e9ki-Madina, sous-pr\u00e9fecture de Kolaboui dans la pr\u00e9fecture de Bok\u00e9.<\/strong><\/p>\n<p>Selon nos sources, c\u2019est le cort\u00e8ge du ministre de la s\u00e9curit\u00e9, Bachir Diallo en partance pour la sous-pr\u00e9fecture de Kamsar qui est entr\u00e9 en collision avec un v\u00e9hicule de transport en commun.<\/p>\n<p>Il faut rappeler que la mission du ministre s\u2019inscrit dans le cadre de l\u2019immersion\u00a0gouvernementale dans l\u2019arri\u00e8re-pays.<\/p>\n<p><strong>Nous y reviendrons\u2026<\/strong><\/p>\n<p><strong>Barry <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Onze morts et 5 bless\u00e9s graves, c\u2019est le triste bilan d\u2019un accident de la route survenu ce lundi 13 juin 2022 aux environs de 10 heures dans le secteur Tambony, district Kar\u00e9ki-Madina, sous-pr\u00e9fecture de Kolaboui dans la pr\u00e9fecture de Bok\u00e9. Selon nos sources, c\u2019est le cort\u00e8ge du ministre de la s\u00e9curit\u00e9, Bachir Diallo en partance [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29586,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"buzzeditor_post_format":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-29585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_featured_media_url":"https:\/\/guineechrono.com\/wp-content\/uploads\/2022\/06\/accidenttt.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/comments?post=29585"}],"version-history":[{"count":0,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media\/29586"}],"wp:attachment":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media?parent=29585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/categories?post=29585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/tags?post=29585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}