{"id":29655,"date":"2022-06-16T17:15:57","date_gmt":"2022-06-16T16:15:57","guid":{"rendered":"https:\/\/guineechrono.com\/?p=29655"},"modified":"2022-06-16T17:15:57","modified_gmt":"2022-06-16T16:15:57","slug":"kindia-colonel-mamadi-doumbouya-en-communion-avec-ses-freres-darme","status":"publish","type":"post","link":"https:\/\/guineechrono.com\/index.php\/kindia-colonel-mamadi-doumbouya-en-communion-avec-ses-freres-darme\/","title":{"rendered":"Kindia : colonel Mamadi Doumbouya en communion avec ses fr\u00e8res d\u2019arme"},"content":{"rendered":"<p>Comme un retour aux sources, le chef de l\u2019Etat s\u2019est rendu ce jeudi dans la ville des agrumes. Il y a pass\u00e9 en revue les troupes avant de s\u2019assurer de l\u2019effectivit\u00e9 des travaux de construction des infrastructures devant concourir \u00e0 l\u2019am\u00e9lioration des conditions de vie des soldats.<\/p>\n<p>Colonel Mamadi DOUMBOUYA pose ses valises \u00e0 Kindia, premi\u00e8re r\u00e9gion militaire du pays. D\u00e9termin\u00e9 \u00e0 faire corps avec les pr\u00e9occupations de ses fr\u00e8res d\u2019armes, il se rend au Camp Samoreya. Au pas de charge, il re\u00e7oit les honneurs militaires au son de l\u2019hymne national. Apr\u00e8s la revue des troupes, le pr\u00e9sident du CNRD plaide pour l\u2019unit\u00e9 de l\u2019arm\u00e9e guin\u00e9enne.<\/p>\n<p>Accompagn\u00e9 de hauts responsables militaires de la r\u00e9gion de Kindia, le chef supr\u00eame des Arm\u00e9es met sa visite \u00e0 profit pour constater de visu certains chantiers. Occasion pour lui de rassurer les hommes de troupe sur sa d\u00e9termination \u00e0 leur garantir des conditions de vie id\u00e9ales. De quoi les galvaniser pour assurer la d\u00e9fense de l\u2019int\u00e9grit\u00e9 territoriale du pays.<\/p>\n<p>En plus de renforcer les liens avec ses fr\u00e8res d\u2019armes, Colonel Mamadi DOUMBOUYA se rappelle aux bons souvenirs de son passage dans la ville des agrumes. Des r\u00e9miniscences de sa trajectoire militaire jalonn\u00e9e de hauts faits, qui assoient sa conviction que lui et l\u2019arm\u00e9e guin\u00e9enne ne font qu\u2019un au b\u00e9n\u00e9fice des Guin\u00e9ens.<\/p>\n<p>\ud835\uddd7\ud835\uddd6\ud835\udddc-\ud835\udde3\ud835\udde5\ud835\uddda<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme un retour aux sources, le chef de l\u2019Etat s\u2019est rendu ce jeudi dans la ville des agrumes. Il y a pass\u00e9 en revue les troupes avant de s\u2019assurer de l\u2019effectivit\u00e9 des travaux de construction des infrastructures devant concourir \u00e0 l\u2019am\u00e9lioration des conditions de vie des soldats. Colonel Mamadi DOUMBOUYA pose ses valises \u00e0 Kindia, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29656,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"buzzeditor_post_format":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-29655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_featured_media_url":"https:\/\/guineechrono.com\/wp-content\/uploads\/2022\/06\/doumm.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/comments?post=29655"}],"version-history":[{"count":0,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media\/29656"}],"wp:attachment":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media?parent=29655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/categories?post=29655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/tags?post=29655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}