{"id":29885,"date":"2022-06-29T12:32:45","date_gmt":"2022-06-29T11:32:45","guid":{"rendered":"https:\/\/guineechrono.com\/?p=29885"},"modified":"2022-06-29T12:32:45","modified_gmt":"2022-06-29T11:32:45","slug":"guinee-enfin-limprimerie-patrice-lumumba-ramenee-dans-le-portefeuille-de-letat-decret","status":"publish","type":"post","link":"https:\/\/guineechrono.com\/index.php\/guinee-enfin-limprimerie-patrice-lumumba-ramenee-dans-le-portefeuille-de-letat-decret\/","title":{"rendered":"Guin\u00e9e : enfin, l\u2019imprimerie Patrice Lumumba ramen\u00e9e dans le portefeuille de l\u2019Etat (d\u00e9cret)"},"content":{"rendered":"<p>Dans un d\u00e9cret publi\u00e9 dans la soir\u00e9e du mardi 28 juin 2022 \u00e0 Conakry, le pr\u00e9sident de la transition a ramen\u00e9 le complexe industriel de l\u2019imprimerie Patrice Lumumba situ\u00e9 \u00e0 Coleah dans la commune de Matam.<\/p>\n<p>\u00ab\u00a0Ledit terrain fait retour au portefeuille de l\u2019Etat, quitte et fin de toutes dettes et charges\u00a0\u00bb, note le d\u00e9cret lu \u00e0 la t\u00e9l\u00e9vision nationale le mardi 28 juin 2022.<\/p>\n<p>Dans le m\u00eame d\u00e9cret, Colonel Mamadi Doumbouya a \u00e9galement annul\u00e9 la cession faite de ce terrain \u00e0 la nouvelle imprimerie de Kaloum (NIK).<\/p>\n<p>Les ministres Secr\u00e9taires g\u00e9n\u00e9raux de la pr\u00e9sidence et celui du commerce de l\u2019industrie et des PME sont charg\u00e9s chacun en ce qui le concerne de veiller \u00e0 l\u2019application du pr\u00e9sent d\u00e9cret.<\/p>\n<p><strong>R\u00e9daction <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans un d\u00e9cret publi\u00e9 dans la soir\u00e9e du mardi 28 juin 2022 \u00e0 Conakry, le pr\u00e9sident de la transition a ramen\u00e9 le complexe industriel de l\u2019imprimerie Patrice Lumumba situ\u00e9 \u00e0 Coleah dans la commune de Matam. \u00ab\u00a0Ledit terrain fait retour au portefeuille de l\u2019Etat, quitte et fin de toutes dettes et charges\u00a0\u00bb, note le d\u00e9cret [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":28984,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"buzzeditor_post_format":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-29885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_featured_media_url":"https:\/\/guineechrono.com\/wp-content\/uploads\/2022\/05\/colll.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/comments?post=29885"}],"version-history":[{"count":0,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media\/28984"}],"wp:attachment":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media?parent=29885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/categories?post=29885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/tags?post=29885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}