{"id":29907,"date":"2022-06-30T13:35:02","date_gmt":"2022-06-30T12:35:02","guid":{"rendered":"https:\/\/guineechrono.com\/?p=29907"},"modified":"2022-06-30T13:35:02","modified_gmt":"2022-06-30T12:35:02","slug":"monsieur-le-pm-bea-sil-vous-plait-rendez-le-tabouret-pour-liberer-le-cnrd-et-le-peuple","status":"publish","type":"post","link":"https:\/\/guineechrono.com\/index.php\/monsieur-le-pm-bea-sil-vous-plait-rendez-le-tabouret-pour-liberer-le-cnrd-et-le-peuple\/","title":{"rendered":"Monsieur le PM B\u00c9A, s\u2019il vous pla\u00eet, rendez le \u00ab tabouret \u00bb pour lib\u00e9rer le CNRD et le peuple"},"content":{"rendered":"<p>\u00c0 la suite de la lecture de cette sortie m\u00e9diatique du Pr\u00e9sident du CNT face \u00e0 ce qu\u2019il conviendrait de consid\u00e9rer d\u00e9sormais comme une crise ouverte dans les relations Institutionnelles entre deux (02) organes traditionnels, cruciaux et politiques de la R\u00e9publique.<\/p>\n<p>Ainsi, la nuit portant conseils et apr\u00e8s m\u00fbres r\u00e9flexions, je suis revenu \u00e0 la conclusion que dans l\u2019int\u00e9r\u00eat sup\u00e9rieur de la nation, le PM B\u00e9a doit accepter de lib\u00e9rer le CNRD auquel nous sommes fonci\u00e8rement attach\u00e9 et qui se pr\u00e9sente comme une sorte d\u2019ultime chance de Refondation de l\u2019Etat en Guin\u00e9e.<\/p>\n<p>En effet, au prix que le peuple attache \u00e0 cette Transition et les t\u00e2tonnements insupportables \u00e0 plusieurs \u00e9gards dans la conduite des affaires publiques, l\u2019homme B\u00c9A ferait mieux de rendre le tablier. En y proc\u00e9dant ainsi, il fait amende honorable et fait rena\u00eetre l\u2019espoir fortement amenuisant, ceci d\u00fb, \u00e0 plusieurs incertitudes du petit temps \u00e9coul\u00e9 et qui ne rassure gu\u00e8re. Plut\u00f4t de l\u2019amener \u00e0 une quelconque perte de temps toujours pr\u00e9judiciable au peuple, dans cet autre projet de pr\u00e9sentation de la d\u00e9claration de la politique g\u00e9n\u00e9rale du gouvernement \u00e0 nos chers Conseillers jouant le noble r\u00f4le de repr\u00e9sentation nationale (du peuple), pour gagner en temps, profitons-en pour renouveler le leadership \u00e0 la Station Primatoriale qui en a fortement besoin.<\/p>\n<p>Je ne me lasserai jamais de rappeler cette citation culte de Napol\u00e9on Bonaparte : \u00ab\u00a0Un gouvernant, est un marchand d\u2019esp\u00e9rance\u00a0\u00bb\u00a0!<\/p>\n<p>De toute \u00e9vidence, aujourd\u2019hui, \u00e0 l\u2019analyse de cette d\u00e9claration publique du tr\u00e8s respect\u00e9 Docteur Dansa Kourouma, Pr\u00e9sident du CNT qui en lui (PM) lan\u00e7ant un ultimatum, celui sens\u00e9 assurer une impulsion (qu\u2019on n\u2019a jamais senti) et la coordination (assez faible pour \u00eatre appr\u00e9ci\u00e9e) de l\u2019action gouvernementale, est un des indicateurs largement suffisants pour tirer toutes les conclusions qui sied.<\/p>\n<p>Au regard de plusieurs observations, ind\u00e9niablement, il en ressort une incomp\u00e9tence notoire de cet ancien machiniste du Centre de Formation Professionnelle (CFP) de Matoto (Entag) propuls\u00e9 dans une carri\u00e8re de fonctionnaire international partie de son appartenance aux familles r\u00e9gnantes (Neveu du c\u00e9l\u00e8bre Diallo Telly, ancien Secr\u00e9taire G\u00e9n\u00e9ral de l\u2019OUA, Ministre de la Justice et en fin martyr de la R\u00e9volution du PDG RDA qui se voulait globale, multiforme et exigeante) de la p\u00e9riode Sekoutoureenne.<\/p>\n<p>Allons-nous, nous \u00e9lite fermer les yeux et continuer par l\u00e2chet\u00e9 et hypocrisie-inertie, dans cette d\u00e9concertante hypocrisie face \u00e0 la d\u00e9fense des int\u00e9r\u00eats majeurs et sup\u00e9rieurs du peuple ?<\/p>\n<p>La feuille de route qu\u2019il a pr\u00e9sent\u00e9e avec faste au Pr\u00e9sident L\u00e9gionnaire le colonel Mamadi DOUMBOUYA, pour le citoyen lambda est une sorte de \u00ab\u00a0petite for\u00eat sacr\u00e9e\u00a0\u00bb que seuls lui B\u00e9a et ses camarades [car il reste dans le jargon juridico-politique qu\u2019une sorte de Primus inter par\u00e8s (Premier de ses pairs) et non ce PM assez pr\u00e9dominant dans un \u00ab\u00a0r\u00e9gime souple\u00a0\u00bb], ce citoyen lambda dis-je, est totalement ignorant de la faisabilit\u00e9 de ce document strat\u00e9gique. Il sollicite, ce qui est de plein droit, s\u2019approprier lors de la d\u00e9claration de politique g\u00e9n\u00e9rale du gouvernement aussi du c\u00f4t\u00e9 offshore de la fameuse feuille de route. Il lui faut conna\u00eetre dans les moindres d\u00e9tails les tenants et les aboutissants en le volet, expression chiffr\u00e9e pour le moment qui n\u2019est que son apanage qu\u2019il partage avec ses camarades initi\u00e9s de la \u00ab\u00a0petite foret sacr\u00e9e \u00bb qui si\u00e8gent dans l\u2019\u00e9quipe gouvernementale. Les sans voix que nous sommes, exigeons plus de transparence dans la gestion fut-elle pr\u00e9visible de nos pauvres sous publics longtemps dilapid\u00e9s par les pr\u00e9c\u00e9dents r\u00e9gimes (ce peuple reste d\u00e9sormais tr\u00e8s exigeant).<\/p>\n<p>En tout \u00e9tat de cause, il est une n\u00e9cessit\u00e9 absolue et un devoir patriotique, d\u2019exiger le d\u00e9part de ce concitoyen qui est \u00e0 ses limites dans cette fonction qui exige de son titulaire, encore plus d\u2019allants, de dynamismes et de proactivit\u00e9 qui font bigrement \u00e0 pr\u00e9sent d\u00e9faut. Nous continuerons de regretter un certain feu Jean Marie Dor\u00e9 (paix \u00e0 son \u00e2me) qui fut en le domaine, une vraie \u00ab\u00a0Ecole\u00a0\u00bb de gouvernant, certes sur une tr\u00e8s courte p\u00e9riode mais tr\u00e8s enrichissante. Le manquement volontaire de sa part \u00e0 cette longue tradition r\u00e9publicaine [Refus de pr\u00e9sentation de la Politique g\u00e9n\u00e9rale du gouvernement aux dignes repr\u00e9sentants du peuple (CNT pour l\u2019instant)] si ch\u00e8re aux nations polic\u00e9es et \u00e0 laquelle vient de se d\u00e9rober immanquablement notre cher grand fr\u00e8re aim\u00e9. Cette d\u00e9fiance ne doit rester sans cons\u00e9quences. Qu\u2019\u00e0 cela ne tienne, il demeurera aussi longtemps qu\u2019il sera dans cette posture, un des fusibles parfaits dans cette gouvernance un peu tanc\u00e9e o\u00f9 le Pr\u00e9sident Colonel Mamadi DOUMBOUYA doit avoir fermement \u00e0 l\u2019id\u00e9e ou \u00e0 l\u2019esprit que toutes les d\u00e9missions ne sont pas souvent volontaires et o\u00f9 parfois, le destinataire peut aussi en exiger (une fa\u00e7on d\u2019offrir une sortie honorable \u00e0 un proche collaborateur tomb\u00e9 en disgr\u00e2ce pour une raison ou une autre).<\/p>\n<p>Ici, pour moi, le d\u00e9terminant ou la seule constante reste : le CNRD et son Pr\u00e9sident Colonel Mamadi DOUMBOUYA (dont la valeur nette est connue d\u2019avance, depuis le 05 septembre 2021), tout le reste, sont des variables (c\u2019est-\u00e0-dire des donn\u00e9es interchangeables \u00e0 souhait, ceci, en fonction des scenarii d\u00e9sir\u00e9s).<\/p>\n<p>Derri\u00e8re cette saine volont\u00e9 individuelle, il n\u2019y a aucune m\u00e9chancet\u00e9, si ce n\u2019est l\u2019expression sinc\u00e8re d\u2019un ras-le-bonbon d\u2019un citoyen d\u2019une lancinante expectative.<\/p>\n<p>Puisse Dieu guider et \u00e9clairer nos pas !<\/p>\n<p>Amen !<\/p>\n<p><strong>Souleymane Doumbouya, Consultant Socio\u00e9conomique<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 la suite de la lecture de cette sortie m\u00e9diatique du Pr\u00e9sident du CNT face \u00e0 ce qu\u2019il conviendrait de consid\u00e9rer d\u00e9sormais comme une crise ouverte dans les relations Institutionnelles entre deux (02) organes traditionnels, cruciaux et politiques de la R\u00e9publique. Ainsi, la nuit portant conseils et apr\u00e8s m\u00fbres r\u00e9flexions, je suis revenu \u00e0 la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29908,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"buzzeditor_post_format":"","footnotes":""},"categories":[2],"tags":[],"class_list":["post-29907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured"],"jetpack_featured_media_url":"https:\/\/guineechrono.com\/wp-content\/uploads\/2022\/06\/ppm.webp","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/comments?post=29907"}],"version-history":[{"count":0,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29907\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media\/29908"}],"wp:attachment":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media?parent=29907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/categories?post=29907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/tags?post=29907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}