{"id":29910,"date":"2022-06-30T14:11:30","date_gmt":"2022-06-30T13:11:30","guid":{"rendered":"https:\/\/guineechrono.com\/?p=29910"},"modified":"2022-06-30T14:11:30","modified_gmt":"2022-06-30T13:11:30","slug":"lancine-sacko-les-partisans-du-rpg-arc-en-ciel-privilegient-la-paix-et-la-quietude-sociale","status":"publish","type":"post","link":"https:\/\/guineechrono.com\/index.php\/lancine-sacko-les-partisans-du-rpg-arc-en-ciel-privilegient-la-paix-et-la-quietude-sociale\/","title":{"rendered":"Lancin\u00e9 SACKO: \u00ab les partisans du RPG-arc-en-ciel privil\u00e9gient la paix et la qui\u00e9tude sociale \u00bb"},"content":{"rendered":"<p><strong>Depuis le 5 septembre 2021, date \u00e0 laquelle, les forces du groupement sp\u00e9cial ont fait le coup d\u2019Etat en renversant Alpha Cond\u00e9, l\u2019ancien parti au pouvoir \u00a0se trouve aujourd\u2019hui \u00e9cart\u00e9 de la gestion du pays.<\/strong><\/p>\n<p>Selon un responsable, les partisans de ce parti se taisent et observent l&rsquo;\u00e9volution de la situation politique en privil\u00e9giant la paix et la qui\u00e9tude sociale.<\/p>\n<p>C\u2019est une annonce de Lancin\u00e9 Sacko, coordinateur du RPG-arc-en-ciel au Royaume Uni. \u00ab\u00a0<em>Les partisans du RPG ARC-EN-CIEL, la majorit\u00e9 silencieuse, se taisent et observent l&rsquo;\u00e9volution de la situation politique en privil\u00e9giant la paix et la qui\u00e9tude sociale\u00a0<\/em>\u00bb, d\u00e9clare Lancin\u00e9 Sacko.<\/p>\n<p><strong>R\u00e9daction <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le 5 septembre 2021, date \u00e0 laquelle, les forces du groupement sp\u00e9cial ont fait le coup d\u2019Etat en renversant Alpha Cond\u00e9, l\u2019ancien parti au pouvoir \u00a0se trouve aujourd\u2019hui \u00e9cart\u00e9 de la gestion du pays. Selon un responsable, les partisans de ce parti se taisent et observent l&rsquo;\u00e9volution de la situation politique en privil\u00e9giant la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29911,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"buzzeditor_post_format":"","footnotes":""},"categories":[43],"tags":[],"class_list":["post-29910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique"],"jetpack_featured_media_url":"https:\/\/guineechrono.com\/wp-content\/uploads\/2022\/06\/ss.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/comments?post=29910"}],"version-history":[{"count":0,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media\/29911"}],"wp:attachment":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media?parent=29910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/categories?post=29910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/tags?post=29910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}