{"id":29999,"date":"2022-07-09T19:24:26","date_gmt":"2022-07-09T18:24:26","guid":{"rendered":"https:\/\/guineechrono.com\/?p=29999"},"modified":"2022-07-09T19:24:26","modified_gmt":"2022-07-09T18:24:26","slug":"celebration-de-laid-el-adha-le-president-de-la-transition-colonel-mamadi-doumbouya-a-accompli-la-priere-au-palais-mohammed-v","status":"publish","type":"post","link":"https:\/\/guineechrono.com\/index.php\/celebration-de-laid-el-adha-le-president-de-la-transition-colonel-mamadi-doumbouya-a-accompli-la-priere-au-palais-mohammed-v\/","title":{"rendered":"C\u00e9l\u00e9bration de l\u2019Aid El-Adha: le Pr\u00e9sident de la Transition, Colonel Mamadi Doumbouya a accompli la pri\u00e8re au Palais Mohammed V"},"content":{"rendered":"<p>Le Pr\u00e9sident de la Transition a accompli la f\u00eate de Tabaski au Palais Mohammed V. Occasion pour lui d\u2019y accomplir son devoir religieux, \u00e0 l\u2019instar de ses coreligionnaires de Boulbinet et autres quartiers adjacents situ\u00e9s dans la commune de Kaloum.<\/p>\n<p>Les membres du Cabinet civil de la Pr\u00e9sidence de la R\u00e9publique ainsi que quelques ministres \u00e9taient pr\u00e9sents \u00e0 ses c\u00f4t\u00e9s pour c\u00e9l\u00e9brer cette f\u00eate dans la ferveur religieuse.<\/p>\n<p>Avec son habituel franc-parler, le premier imam de la Grande Mosqu\u00e9e Fay\u00e7al, El Hadj Mamadou Saliou Camara, qui a offici\u00e9 la pri\u00e8re, s\u2019est longuement \u00e9tendu, dans son sermon, sur les implications religieuses de la f\u00eate de la Tabaski pour les musulmans. Il a mis l\u2019occasion \u00e0 profit pour exhorter les Guin\u00e9ens \u00e0 un sursaut patriotique en transcendant leurs divergences pour privil\u00e9gier la paix, le pardon et le dialogue, indispensables, selon lui, \u00e0 la r\u00e9ussite de la Transition en cours.<\/p>\n<p>\ud835\uddd7\ud835\uddd6\ud835\udddc- \ud835\udde3\ud835\udde5\ud835\uddda<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident de la Transition a accompli la f\u00eate de Tabaski au Palais Mohammed V. Occasion pour lui d\u2019y accomplir son devoir religieux, \u00e0 l\u2019instar de ses coreligionnaires de Boulbinet et autres quartiers adjacents situ\u00e9s dans la commune de Kaloum. Les membres du Cabinet civil de la Pr\u00e9sidence de la R\u00e9publique ainsi que quelques ministres [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30001,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"buzzeditor_post_format":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-29999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_featured_media_url":"https:\/\/guineechrono.com\/wp-content\/uploads\/2022\/07\/fetes-1.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/comments?post=29999"}],"version-history":[{"count":0,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/29999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media\/30001"}],"wp:attachment":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media?parent=29999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/categories?post=29999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/tags?post=29999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}