{"id":30113,"date":"2022-07-19T13:24:48","date_gmt":"2022-07-19T12:24:48","guid":{"rendered":"https:\/\/guineechrono.com\/?p=30113"},"modified":"2022-07-19T13:24:48","modified_gmt":"2022-07-19T12:24:48","slug":"vous-devez-a-mon-avis-revoir-le-budget-alloue-a-leducation-lettre-ouverte-au-colonel-mamadi-doumbouya","status":"publish","type":"post","link":"https:\/\/guineechrono.com\/index.php\/vous-devez-a-mon-avis-revoir-le-budget-alloue-a-leducation-lettre-ouverte-au-colonel-mamadi-doumbouya\/","title":{"rendered":"\u00ab Vous devez \u00e0 mon avis revoir le budget allou\u00e9 \u00e0 l\u2019\u00e9ducation \u00bb (lettre ouverte au Colonel Mamadi Doumbouya)"},"content":{"rendered":"<p>Lettre ouverte au Colonel\u00a0Doumbouya<\/p>\n<p>Monsieur le Pr\u00e9sident,<\/p>\n<p>En 2010, un professeur venu de Sorbonne a h\u00e9rit\u00e9 d\u2019un pays et non d\u2019un \u00c9tat. Et, tr\u00e8s malheureusement, plut\u00f4t que de transformer ce pays en \u00c9tat, il l\u2019a transform\u00e9 en jungle.<\/p>\n<p>Mon colonel, je suis d\u2019accord comme tous les Guin\u00e9ens que vous n\u2019\u00eates pas directement comptable de la situation que vous avez trouv\u00e9e le 5 septembre 2021. Cependant, en bon patriote comme vous vous d\u00e9crivez, vous pouvez laisser des traces ind\u00e9l\u00e9biles dans certains domaines dont l\u2019\u00e9ducation en premier.<\/p>\n<p>Mon colonel, connaissant votre parcours, il suffit juste d\u2019avoir une volont\u00e9 politique pour que notre syst\u00e8me \u00e9ducatif trouve la voie qui lui faut pour occuper sa place sur l\u2019\u00e9chiquier mondial.<\/p>\n<p>Mon colonel, autant un militaire mal form\u00e9 est un danger pour la R\u00e9publique, autant un enfant sans \u00e9ducation est un cancer pour elle.<\/p>\n<p>Militaire que vous \u00eates, p\u00e8re de famille que vous \u00eates, ayant la destin\u00e9e de la nation aujourd\u2019hui, vous avez les moyens, le pouvoir et donc l\u2019obligation de r\u00e9server \u00e0 chaque enfant une \u00e9ducation s\u00fbre et enviable.<\/p>\n<p>Pour cela, je vous \u00e9num\u00e8re ci-dessous ces quelques points qui, \u00e0 mon entendement, sont indispensables pour la qualification de notre syst\u00e8me \u00e9ducatif.<\/p>\n<p>1- Vous devez \u00e0 mon avis revoir le budget allou\u00e9 \u00e0 l\u2019\u00e9ducation. S\u2019il ne peut pas d\u00e9passer celui de l\u2019arm\u00e9e, qu\u2019il n\u2019en soit pas moins.<\/p>\n<p>2- Rendez obligatoire l\u2019\u00e9cole d\u00e8s l\u2019\u00e2ge de 3 ans<\/p>\n<p>3-Limitez \u00e0 30 le nombre d\u2019\u00e9l\u00e8ves par classe. (\u00c9tablissements publics comme priv\u00e9s)<\/p>\n<p>4- Instaurez un carnet de correspondance entre encadreurs et parents de la 1\u00e8re ann\u00e9e jusqu\u2019en terminale. Ce carnet servira de moyen d\u2019\u00e9changes entre les professeurs et les parents. Le nombre de pages \u00e9tant connu, l\u2019\u00e9l\u00e8ve ne peut rien y retirer et les parents doivent consulter ce carnet chaque jour au retour des enfants.<\/p>\n<p>5- Exigez que les formateurs soient issus des \u00e9coles d\u00e9di\u00e9es au m\u00e9tier de l\u2019enseignement<\/p>\n<p>6- Rehaussez le salaire des enseignants.<\/p>\n<p>7-Rendez obligatoire la liste des parents d\u2019\u00e9l\u00e8ves avec contacts \u00e0 l\u2019appui dans chaque \u00e9tablissement (Public\/Priv\u00e9).<\/p>\n<p>6-Exigez des parents des explications pour chaque absence constat\u00e9e d\u2019un \u00e9l\u00e8ve. Si cela se r\u00e9p\u00e8te, r\u00e9cup\u00e9rez l\u2019enfant et mettez-le en adoption dans une famille ou un centre qui saura s\u2019occuper de lui.<\/p>\n<p>8- Investissez dans les \u00e9difices (\u00c9coles, biblioth\u00e8ques, terrains de foot, tennis, basket \u2026) car, les enfants apprennent plus vite dans la blague que dans le s\u00e9rieux.<\/p>\n<p>9- Supprimez les examens CEP et BEPC. Aucun enfant ne doit \u00eatre bloqu\u00e9 avant le niveau BAC. Au BAC, soit on est admis dans une universit\u00e9, soit dans une \u00e9cole professionnelle. De toute fa\u00e7on, chacun doit avoir une qualification pour le bien de la soci\u00e9t\u00e9.<\/p>\n<p>Voil\u00e0, Monsieur le pr\u00e9sident, ma petite id\u00e9e pour permettre \u00e0 notre pays de rehausser le niveau d\u2019alphab\u00e9tisation et d\u2019avoir une population qualifi\u00e9e et active.<\/p>\n<p>Mohamed CISSE<\/p>\n<p>Pr\u00e9sident de LaNG<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lettre ouverte au Colonel\u00a0Doumbouya Monsieur le Pr\u00e9sident, En 2010, un professeur venu de Sorbonne a h\u00e9rit\u00e9 d\u2019un pays et non d\u2019un \u00c9tat. Et, tr\u00e8s malheureusement, plut\u00f4t que de transformer ce pays en \u00c9tat, il l\u2019a transform\u00e9 en jungle. Mon colonel, je suis d\u2019accord comme tous les Guin\u00e9ens que vous n\u2019\u00eates pas directement comptable de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30114,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"buzzeditor_post_format":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-30113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_featured_media_url":"https:\/\/guineechrono.com\/wp-content\/uploads\/2022\/07\/cissee.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/30113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/comments?post=30113"}],"version-history":[{"count":0,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/30113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media\/30114"}],"wp:attachment":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media?parent=30113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/categories?post=30113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/tags?post=30113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}