{"id":30217,"date":"2023-03-27T13:00:51","date_gmt":"2023-03-27T12:00:51","guid":{"rendered":"https:\/\/guineechrono.com\/?p=30217"},"modified":"2023-03-27T13:00:51","modified_gmt":"2023-03-27T12:00:51","slug":"alpha-kola-balde-sur-le-deces-de-sans-loi-au-revoir-babaen-mawdho","status":"publish","type":"post","link":"https:\/\/guineechrono.com\/index.php\/alpha-kola-balde-sur-le-deces-de-sans-loi-au-revoir-babaen-mawdho\/","title":{"rendered":"Alpha Kola Bald\u00e9 sur le d\u00e9c\u00e8s de \u2018\u2019Sans loi\u2019\u2019 : \u00ab Au revoir Babaen Mawdho !! \u00bb"},"content":{"rendered":"<p>C&rsquo;est avec une vague d&rsquo;\u00e9motions que j&rsquo;ai appris le rappel \u00e0 Dieu de l&rsquo;illustre baobab El Hadj Ousmane Fatako BALDE (Sans loi), Pr\u00e9sident de la Coordination Nationale des Foulbh\u00e9 &amp; Haali Poular de Guin\u00e9e.<\/p>\n<p>Il est venu, il a v\u00e9cu &amp; il a vaincu!<\/p>\n<p>Seule l&rsquo;in\u00e9vitable a eu raison sur lui.<\/p>\n<p>\u00ab\u00a0Tr\u00e8s certainement toute \u00e2me go\u00fbtera \u00e0 la mort et vers Dieu est le retour ultime!\u00a0\u00bb<\/p>\n<p>Mes condol\u00e9ances \u00e0 la famille, au Fouta &amp; au peuple de Guin\u00e9e.<\/p>\n<p>Que le Paradis soit sa demeure \u00e9ternelle.<\/p>\n<p><strong>A.K.B<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est avec une vague d&rsquo;\u00e9motions que j&rsquo;ai appris le rappel \u00e0 Dieu de l&rsquo;illustre baobab El Hadj Ousmane Fatako BALDE (Sans loi), Pr\u00e9sident de la Coordination Nationale des Foulbh\u00e9 &amp; Haali Poular de Guin\u00e9e. Il est venu, il a v\u00e9cu &amp; il a vaincu! Seule l&rsquo;in\u00e9vitable a eu raison sur lui. \u00ab\u00a0Tr\u00e8s certainement toute \u00e2me [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30219,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"buzzeditor_post_format":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-30217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_featured_media_url":"https:\/\/guineechrono.com\/wp-content\/uploads\/2023\/03\/sans-loi.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/30217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/comments?post=30217"}],"version-history":[{"count":0,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/30217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media\/30219"}],"wp:attachment":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media?parent=30217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/categories?post=30217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/tags?post=30217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}