{"id":30267,"date":"2023-03-31T11:03:47","date_gmt":"2023-03-31T10:03:47","guid":{"rendered":"https:\/\/guineechrono.com\/?p=30267"},"modified":"2023-03-31T11:03:47","modified_gmt":"2023-03-31T10:03:47","slug":"ouganda-le-fils-du-president-promet-denvoyer-des-troupes-pour-defendre-moscou","status":"publish","type":"post","link":"https:\/\/guineechrono.com\/index.php\/ouganda-le-fils-du-president-promet-denvoyer-des-troupes-pour-defendre-moscou\/","title":{"rendered":"Ouganda : le fils du pr\u00e9sident promet d\u2019envoyer des troupes pour d\u00e9fendre Moscou"},"content":{"rendered":"<p>Le fils du chef de l\u2019Etat ougandais Yoweri Museveni, Muhoozi Kainerugaba, a affirm\u00e9 qu\u2019il enverrait des troupes ougandaises pour d\u00e9fendre Moscou en cas de menace \u00ab\u00a0imp\u00e9rialiste\u00a0\u00bb.<\/p>\n<p><em>\u00ab\u00a0Appelez-moi \u2018poutiniste\u2019 si vous voulez, nous l\u2019Ouganda, devrions envoyer des soldats pour d\u00e9fendre Moscou si jamais elle \u00e9tait menac\u00e9e par les imp\u00e9rialistes\u00a0\u00bb<\/em>, a-t-il \u00e9crit sur Twitter.\u00a0<em>\u00ab\u00a0L\u2019Occident perd son temps avec la propagande pro-ukrainienne inutile\u00a0\u00bb<\/em>, a ajout\u00e9 le fils du pr\u00e9sident, fervent soutien de Vladimir Poutine.<\/p>\n<p>Il a \u00e9galement annonc\u00e9 jeudi la cr\u00e9ation d\u2019une cha\u00eene de t\u00e9l\u00e9vision et de radio portant sa marque, \u00ab\u00a0MK\u00a0\u00bb. M. Kainerugaba, 48 ans, habitu\u00e9 des d\u00e9clarations pol\u00e9miques sur Twitter, a annonc\u00e9 ce mois-ci sa candidature \u00e0 la pr\u00e9sidentielle de 2026.<\/p>\n<p>Le 18 octobre 2022, Yoweri Museveni avait d\u00e9clar\u00e9 que son unique fils \u2013 il a \u00e9galement trois filles \u2013 ne tweeterait plus sur les affaires du pays, apr\u00e8s une s\u00e9rie de tweets pol\u00e9miques d\u00e9but octobre o\u00f9 il avait notamment menac\u00e9 d\u2019envahir le Kenya.<\/p>\n<p>L\u2019Ouganda s\u2019est abstenu lors des votes \u00e0 l\u2019ONU sur le conflit ukrainien, dont celui en f\u00e9vrier au moment du premier anniversaire de l\u2019invasion russe en Ukraine, qui appelait Moscou \u00e0 un retrait de ses troupes du pays. En juillet, lors d\u2019une tourn\u00e9e en Afrique du ministre des Affaires \u00e9trang\u00e8res russe Sergei Lavrov, M. Kainerugaba avait d\u00e9clar\u00e9, en faisant allusion \u00e0 la Russie:\u00a0<em>\u00ab\u00a0Comment pouvons-nous \u00eatre contre quelqu\u2019un qui ne nous a jamais fait de mal\u00a0\u00bb<\/em>.<\/p>\n<p>La Russie a traditionnellement des liens forts avec l\u2019Afrique en raison de son aide apport\u00e9e aux mouvements d\u2019ind\u00e9pendance sur le continent alors aux prises avec des puissances coloniales. Les observateurs ont longtemps consid\u00e9r\u00e9 que Muhoozi Kainerugaba \u00e9tait pressenti pour prendre la succession de son p\u00e8re Yoweri Museveni, \u00e2g\u00e9 de 78 ans.<\/p>\n<p><strong>AFP<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le fils du chef de l\u2019Etat ougandais Yoweri Museveni, Muhoozi Kainerugaba, a affirm\u00e9 qu\u2019il enverrait des troupes ougandaises pour d\u00e9fendre Moscou en cas de menace \u00ab\u00a0imp\u00e9rialiste\u00a0\u00bb. \u00ab\u00a0Appelez-moi \u2018poutiniste\u2019 si vous voulez, nous l\u2019Ouganda, devrions envoyer des soldats pour d\u00e9fendre Moscou si jamais elle \u00e9tait menac\u00e9e par les imp\u00e9rialistes\u00a0\u00bb, a-t-il \u00e9crit sur Twitter.\u00a0\u00ab\u00a0L\u2019Occident perd son temps [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30268,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"buzzeditor_post_format":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-30267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_featured_media_url":"https:\/\/guineechrono.com\/wp-content\/uploads\/2023\/03\/ouganda.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/30267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/comments?post=30267"}],"version-history":[{"count":0,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/30267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media\/30268"}],"wp:attachment":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media?parent=30267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/categories?post=30267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/tags?post=30267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}