{"id":30279,"date":"2023-03-31T19:18:43","date_gmt":"2023-03-31T18:18:43","guid":{"rendered":"https:\/\/guineechrono.com\/?p=30279"},"modified":"2023-03-31T19:29:14","modified_gmt":"2023-03-31T18:29:14","slug":"acquisition-de-materiels-informatiques-edg-lance-un-appel-doffres-national","status":"publish","type":"post","link":"https:\/\/guineechrono.com\/index.php\/acquisition-de-materiels-informatiques-edg-lance-un-appel-doffres-national\/","title":{"rendered":"Acquisition de mat\u00e9riels informatiques : EDG lance un appel d\u2019offres national"},"content":{"rendered":"<p><strong>La Soci\u00e9t\u00e9 Electricit\u00e9 de Guin\u00e9e (EDG-SA), lance un avis d\u2019Appel d\u2019Offres National Ouvert dans le cadre de l\u2019informatisation des services et de l\u2019am\u00e9lioration de la qualit\u00e9 de travail de ses employ\u00e9s. <\/strong><\/p>\n<p><strong>Ci-dessous l\u2019int\u00e9gralit\u00e9 dudit communiqu\u00e9 :<\/strong><\/p>\n<p><a href=\"https:\/\/guineechrono.com\/wp-content\/uploads\/2023\/03\/copie-edg.pdf\">copie edg<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Soci\u00e9t\u00e9 Electricit\u00e9 de Guin\u00e9e (EDG-SA), lance un avis d\u2019Appel d\u2019Offres National Ouvert dans le cadre de l\u2019informatisation des services et de l\u2019am\u00e9lioration de la qualit\u00e9 de travail de ses employ\u00e9s. Ci-dessous l\u2019int\u00e9gralit\u00e9 dudit communiqu\u00e9 : copie edg &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":30281,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"buzzeditor_post_format":"","footnotes":""},"categories":[42],"tags":[],"class_list":["post-30279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_featured_media_url":"https:\/\/guineechrono.com\/wp-content\/uploads\/2023\/03\/eee.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/30279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/comments?post=30279"}],"version-history":[{"count":0,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/posts\/30279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media\/30281"}],"wp:attachment":[{"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/media?parent=30279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/categories?post=30279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineechrono.com\/index.php\/wp-json\/wp\/v2\/tags?post=30279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}